{"id":5576,"date":"2024-01-04T15:47:43","date_gmt":"2024-01-04T14:47:43","guid":{"rendered":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads.webp"},"modified":"2024-01-04T15:47:43","modified_gmt":"2024-01-04T14:47:43","slug":"tensor-threads-2","status":"inherit","type":"attachment","link":"https:\/\/www.medespoir.ch\/blog\/de\/tensor-threads-2\/","title":{"rendered":"tensor-threads"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-5576","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>tensor-threads - Actualit\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medespoir.ch\/blog\/de\/tensor-threads-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"tensor-threads - Actualit\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medespoir.ch\/blog\/de\/tensor-threads-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1072\" \/>\n\t<meta property=\"og:image:height\" content=\"1136\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/de\\\/tensor-threads-2\\\/\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/de\\\/tensor-threads-2\\\/\",\"name\":\"tensor-threads - Actualit\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/de\\\/#website\"},\"datePublished\":\"2024-01-04T14:47:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/de\\\/tensor-threads-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/de\\\/tensor-threads-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/de\\\/tensor-threads-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"tensor-threads\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/de\\\/\",\"name\":\"Actualit\u00e9s\",\"description\":\"tout ce qui est en rapport avec la chirurgie esth\u00e9tique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"tensor-threads - Actualit\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medespoir.ch\/blog\/de\/tensor-threads-2\/","og_locale":"de_DE","og_type":"article","og_title":"tensor-threads - Actualit\u00e9s","og_url":"https:\/\/www.medespoir.ch\/blog\/de\/tensor-threads-2\/","og_site_name":"Actualit\u00e9s","og_image":[{"width":1072,"height":1136,"url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.medespoir.ch\/blog\/de\/tensor-threads-2\/","url":"https:\/\/www.medespoir.ch\/blog\/de\/tensor-threads-2\/","name":"tensor-threads - Actualit\u00e9s","isPartOf":{"@id":"https:\/\/www.medespoir.ch\/blog\/de\/#website"},"datePublished":"2024-01-04T14:47:43+00:00","breadcrumb":{"@id":"https:\/\/www.medespoir.ch\/blog\/de\/tensor-threads-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medespoir.ch\/blog\/de\/tensor-threads-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.medespoir.ch\/blog\/de\/tensor-threads-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.medespoir.ch\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"tensor-threads"}]},{"@type":"WebSite","@id":"https:\/\/www.medespoir.ch\/blog\/de\/#website","url":"https:\/\/www.medespoir.ch\/blog\/de\/","name":"Actualit\u00e9s","description":"tout ce qui est en rapport avec la chirurgie esth\u00e9tique","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medespoir.ch\/blog\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads.webp'><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"300\" src=\"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads-283x300.webp\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads-283x300.webp 283w, https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads-966x1024.webp 966w, https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads-768x814.webp 768w, https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads-255x270.webp 255w, https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads.webp 1072w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/webp","media_details":{"width":1072,"height":1136,"file":"2024\/01\/tensor-threads.webp","filesize":52090,"sizes":{"medium":{"file":"tensor-threads-283x300.webp","width":283,"height":300,"filesize":5668,"mime_type":"image\/webp","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads-283x300.webp"},"large":{"file":"tensor-threads-966x1024.webp","width":966,"height":1024,"filesize":35220,"mime_type":"image\/webp","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads-966x1024.webp"},"thumbnail":{"file":"tensor-threads-150x150.webp","width":150,"height":150,"filesize":2516,"mime_type":"image\/webp","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads-150x150.webp"},"medium_large":{"file":"tensor-threads-768x814.webp","width":768,"height":814,"filesize":23398,"mime_type":"image\/webp","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads-768x814.webp"},"post-thumbnail":{"file":"tensor-threads-255x270.webp","width":255,"height":270,"filesize":4944,"mime_type":"image\/webp","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads-255x270.webp"},"nisarg-full-width":{"file":"tensor-threads-1038x576.webp","width":1038,"height":576,"filesize":23806,"mime_type":"image\/webp","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads-1038x576.webp"},"full":{"file":"tensor-threads.webp","width":1072,"height":1136,"mime_type":"image\/webp","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads.webp"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/01\/tensor-threads.webp","filename":"tensor-threads.webp","filesize":52090,"_links":{"self":[{"href":"https:\/\/www.medespoir.ch\/blog\/de\/wp-json\/wp\/v2\/media\/5576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medespoir.ch\/blog\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.medespoir.ch\/blog\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/de\/wp-json\/wp\/v2\/comments?post=5576"}]}}