{"id":7577,"date":"2024-07-23T14:39:01","date_gmt":"2024-07-23T12:39:01","guid":{"rendered":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses.jpg"},"modified":"2024-07-23T14:39:11","modified_gmt":"2024-07-23T12:39:11","slug":"greffe-cheveux-suisses","status":"inherit","type":"attachment","link":"https:\/\/www.medespoir.ch\/blog\/greffe-cheveux-pour-suisses\/greffe-cheveux-suisses\/","title":{"rendered":"greffe-cheveux-suisses"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-7577","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>greffe-cheveux-suisses - Actualit\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medespoir.ch\/blog\/greffe-cheveux-pour-suisses\/greffe-cheveux-suisses\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"greffe-cheveux-suisses - Actualit\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medespoir.ch\/blog\/greffe-cheveux-pour-suisses\/greffe-cheveux-suisses\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-23T12:39:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1430\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/greffe-cheveux-pour-suisses\\\/greffe-cheveux-suisses\\\/\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/greffe-cheveux-pour-suisses\\\/greffe-cheveux-suisses\\\/\",\"name\":\"greffe-cheveux-suisses - Actualit\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#website\"},\"datePublished\":\"2024-07-23T12:39:01+00:00\",\"dateModified\":\"2024-07-23T12:39:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/greffe-cheveux-pour-suisses\\\/greffe-cheveux-suisses\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/greffe-cheveux-pour-suisses\\\/greffe-cheveux-suisses\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/greffe-cheveux-pour-suisses\\\/greffe-cheveux-suisses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Greffe cheveux pour Suisses en Tunisie : guide et tarifs\",\"item\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/greffe-cheveux-pour-suisses\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"greffe-cheveux-suisses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/\",\"name\":\"Actualit\u00e9s\",\"description\":\"tout ce qui est en rapport avec la chirurgie esth\u00e9tique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"greffe-cheveux-suisses - Actualit\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medespoir.ch\/blog\/greffe-cheveux-pour-suisses\/greffe-cheveux-suisses\/","og_locale":"fr_FR","og_type":"article","og_title":"greffe-cheveux-suisses - Actualit\u00e9s","og_url":"https:\/\/www.medespoir.ch\/blog\/greffe-cheveux-pour-suisses\/greffe-cheveux-suisses\/","og_site_name":"Actualit\u00e9s","article_modified_time":"2024-07-23T12:39:11+00:00","og_image":[{"width":1430,"height":600,"url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.medespoir.ch\/blog\/greffe-cheveux-pour-suisses\/greffe-cheveux-suisses\/","url":"https:\/\/www.medespoir.ch\/blog\/greffe-cheveux-pour-suisses\/greffe-cheveux-suisses\/","name":"greffe-cheveux-suisses - Actualit\u00e9s","isPartOf":{"@id":"https:\/\/www.medespoir.ch\/blog\/#website"},"datePublished":"2024-07-23T12:39:01+00:00","dateModified":"2024-07-23T12:39:11+00:00","breadcrumb":{"@id":"https:\/\/www.medespoir.ch\/blog\/greffe-cheveux-pour-suisses\/greffe-cheveux-suisses\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medespoir.ch\/blog\/greffe-cheveux-pour-suisses\/greffe-cheveux-suisses\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.medespoir.ch\/blog\/greffe-cheveux-pour-suisses\/greffe-cheveux-suisses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.medespoir.ch\/blog\/"},{"@type":"ListItem","position":2,"name":"Greffe cheveux pour Suisses en Tunisie : guide et tarifs","item":"https:\/\/www.medespoir.ch\/blog\/greffe-cheveux-pour-suisses\/"},{"@type":"ListItem","position":3,"name":"greffe-cheveux-suisses"}]},{"@type":"WebSite","@id":"https:\/\/www.medespoir.ch\/blog\/#website","url":"https:\/\/www.medespoir.ch\/blog\/","name":"Actualit\u00e9s","description":"tout ce qui est en rapport avec la chirurgie esth\u00e9tique","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medespoir.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"126\" src=\"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses-300x126.jpg\" class=\"attachment-medium size-medium\" alt=\"greffe cheveux Suisses\" srcset=\"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses-300x126.jpg 300w, https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses-1024x430.jpg 1024w, https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses-768x322.jpg 768w, https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses-604x253.jpg 604w, https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses.jpg 1430w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"greffe cheveux Suisses","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1430,"height":600,"file":"2024\/07\/greffe-cheveux-suisses.jpg","filesize":183981,"sizes":{"medium":{"file":"greffe-cheveux-suisses-300x126.jpg","width":300,"height":126,"filesize":8579,"mime_type":"image\/jpeg","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses-300x126.jpg"},"large":{"file":"greffe-cheveux-suisses-1024x430.jpg","width":1024,"height":430,"filesize":57480,"mime_type":"image\/jpeg","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses-1024x430.jpg"},"thumbnail":{"file":"greffe-cheveux-suisses-150x150.jpg","width":150,"height":150,"filesize":4628,"mime_type":"image\/jpeg","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses-150x150.jpg"},"medium_large":{"file":"greffe-cheveux-suisses-768x322.jpg","width":768,"height":322,"filesize":36803,"mime_type":"image\/jpeg","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses-768x322.jpg"},"post-thumbnail":{"file":"greffe-cheveux-suisses-604x253.jpg","width":604,"height":253,"filesize":25143,"mime_type":"image\/jpeg","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses-604x253.jpg"},"nisarg-full-width":{"file":"greffe-cheveux-suisses-1038x576.jpg","width":1038,"height":576,"filesize":73036,"mime_type":"image\/jpeg","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses-1038x576.jpg"},"full":{"file":"greffe-cheveux-suisses.jpg","width":1430,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":7573,"source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/greffe-cheveux-suisses.jpg","filename":"greffe-cheveux-suisses.jpg","filesize":183981,"_links":{"self":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/media\/7577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/comments?post=7577"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":7573,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts\/7573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}