{"id":7682,"date":"2024-07-26T12:45:20","date_gmt":"2024-07-26T10:45:20","guid":{"rendered":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/reduction-levres-suisse.jpg"},"modified":"2024-07-26T12:45:20","modified_gmt":"2024-07-26T10:45:20","slug":"reduction-levres-suisse","status":"inherit","type":"attachment","link":"https:\/\/www.medespoir.ch\/blog\/nymphoplastie-reduction-levres-inferieures-pour-suisses\/reduction-levres-suisse\/","title":{"rendered":"reduction-levres-suisse"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-7682","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>reduction-levres-suisse - Actualit\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medespoir.ch\/blog\/nymphoplastie-reduction-levres-inferieures-pour-suisses\/reduction-levres-suisse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"reduction-levres-suisse - Actualit\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medespoir.ch\/blog\/nymphoplastie-reduction-levres-inferieures-pour-suisses\/reduction-levres-suisse\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/reduction-levres-suisse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/nymphoplastie-reduction-levres-inferieures-pour-suisses\\\/reduction-levres-suisse\\\/\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/nymphoplastie-reduction-levres-inferieures-pour-suisses\\\/reduction-levres-suisse\\\/\",\"name\":\"reduction-levres-suisse - Actualit\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#website\"},\"datePublished\":\"2024-07-26T10:45:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/nymphoplastie-reduction-levres-inferieures-pour-suisses\\\/reduction-levres-suisse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/nymphoplastie-reduction-levres-inferieures-pour-suisses\\\/reduction-levres-suisse\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/nymphoplastie-reduction-levres-inferieures-pour-suisses\\\/reduction-levres-suisse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nymphoplastie et r\u00e9duction l\u00e8vres inf\u00e9rieures pour Suisses : guide complet et tarifs\",\"item\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/nymphoplastie-reduction-levres-inferieures-pour-suisses\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"reduction-levres-suisse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/\",\"name\":\"Actualit\u00e9s\",\"description\":\"tout ce qui est en rapport avec la chirurgie esth\u00e9tique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"reduction-levres-suisse - Actualit\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medespoir.ch\/blog\/nymphoplastie-reduction-levres-inferieures-pour-suisses\/reduction-levres-suisse\/","og_locale":"fr_FR","og_type":"article","og_title":"reduction-levres-suisse - Actualit\u00e9s","og_url":"https:\/\/www.medespoir.ch\/blog\/nymphoplastie-reduction-levres-inferieures-pour-suisses\/reduction-levres-suisse\/","og_site_name":"Actualit\u00e9s","og_image":[{"url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/reduction-levres-suisse.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.medespoir.ch\/blog\/nymphoplastie-reduction-levres-inferieures-pour-suisses\/reduction-levres-suisse\/","url":"https:\/\/www.medespoir.ch\/blog\/nymphoplastie-reduction-levres-inferieures-pour-suisses\/reduction-levres-suisse\/","name":"reduction-levres-suisse - Actualit\u00e9s","isPartOf":{"@id":"https:\/\/www.medespoir.ch\/blog\/#website"},"datePublished":"2024-07-26T10:45:20+00:00","breadcrumb":{"@id":"https:\/\/www.medespoir.ch\/blog\/nymphoplastie-reduction-levres-inferieures-pour-suisses\/reduction-levres-suisse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medespoir.ch\/blog\/nymphoplastie-reduction-levres-inferieures-pour-suisses\/reduction-levres-suisse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.medespoir.ch\/blog\/nymphoplastie-reduction-levres-inferieures-pour-suisses\/reduction-levres-suisse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.medespoir.ch\/blog\/"},{"@type":"ListItem","position":2,"name":"Nymphoplastie et r\u00e9duction l\u00e8vres inf\u00e9rieures pour Suisses : guide complet et tarifs","item":"https:\/\/www.medespoir.ch\/blog\/nymphoplastie-reduction-levres-inferieures-pour-suisses\/"},{"@type":"ListItem","position":3,"name":"reduction-levres-suisse"}]},{"@type":"WebSite","@id":"https:\/\/www.medespoir.ch\/blog\/#website","url":"https:\/\/www.medespoir.ch\/blog\/","name":"Actualit\u00e9s","description":"tout ce qui est en rapport avec la chirurgie esth\u00e9tique","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medespoir.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/reduction-levres-suisse.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"192\" src=\"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/reduction-levres-suisse-300x192.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/reduction-levres-suisse-300x192.jpg 300w, https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/reduction-levres-suisse-422x270.jpg 422w, https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/reduction-levres-suisse.jpg 756w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":756,"height":484,"file":"2024\/07\/reduction-levres-suisse.jpg","filesize":96993,"sizes":{"medium":{"file":"reduction-levres-suisse-300x192.jpg","width":300,"height":192,"filesize":8883,"mime_type":"image\/jpeg","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/reduction-levres-suisse-300x192.jpg"},"thumbnail":{"file":"reduction-levres-suisse-150x150.jpg","width":150,"height":150,"filesize":4381,"mime_type":"image\/jpeg","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/reduction-levres-suisse-150x150.jpg"},"post-thumbnail":{"file":"reduction-levres-suisse-422x270.jpg","width":422,"height":270,"filesize":15621,"mime_type":"image\/jpeg","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/reduction-levres-suisse-422x270.jpg"},"full":{"file":"reduction-levres-suisse.jpg","width":756,"height":484,"mime_type":"image\/jpeg","source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/reduction-levres-suisse.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":7680,"source_url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2024\/07\/reduction-levres-suisse.jpg","filename":"reduction-levres-suisse.jpg","filesize":96993,"_links":{"self":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/media\/7682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/comments?post=7682"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":7680,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts\/7680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}