{"id":1471,"date":"2020-07-15T17:53:41","date_gmt":"2020-07-15T15:53:41","guid":{"rendered":"http:\/\/www.medespoir.ch\/blog\/?p=1471"},"modified":"2021-03-18T09:08:02","modified_gmt":"2021-03-18T08:08:02","slug":"comment-traiter-les-vergetures","status":"publish","type":"post","link":"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/","title":{"rendered":"Vergetures : comment les traiter  ?"},"content":{"rendered":"<p><strong>Les\u00a0\u00a0<\/strong><strong>vergetures<\/strong>\u00a0, connues sous le nom\u00a0<strong><em>striae distensae<\/em><\/strong>\u00a0en termes scientifiques, font partie des imperfections de la peau les plus courantes . Les vergetures peuvent se former sur la peau de n&rsquo;importe quelle personne, quel que soit le sexe, quelque soit l&rsquo;age\u00a0et quelque soit le type de la peau.\u00a0Les vergetures affectent les femmes environ deux fois de plus que les hommes . Elles sont des probl\u00e8mes typiques de l&rsquo;adolescence, de la grossesse ou des maladies pond\u00e9rales telles que l&rsquo;ob\u00e9sit\u00e9. les vergetures\u00a0sont \u00e9galement dues \u00e0 des changements soudains de poids (g\u00e9n\u00e9ralement des augmentations soudaines). Ils peuvent se produire pratiquement partout sur le corps, mais les zones les plus touch\u00e9es sont les hanches, les fesses, le dos, les seins, l&rsquo;abdomen et les bras. Les vergetures sont de v\u00e9ritables cicatrices sur la peau en raison\u00a0<strong>des fibres \u00e9lastiques cass\u00e9es dans la couche du derme<\/strong>\u00a0. Quand elles sont plus r\u00e9centes les vergetures\u00a0sont rouges on les appellent scientifiquement (<strong><em>rubrae striae<\/em><\/strong>\u00a0), tandis que les plus \u00ab\u00a0anciennes\u00a0\u00bb sont blanches et appel\u00e9es scientifiquement (<strong><em>\u00a0striae\u00a0<\/em><\/strong><em><strong>albae<\/strong><\/em><em>\u00a0).\u00a0<\/em>Pour cette raison il faut identifier\u00a0les<strong>\u00a0causes des<\/strong>\u00a0vergetures, identifier la pr\u00e9vention et trouver les meilleures rem\u00e8des pour les \u00e9liminer.<\/p>\n<h3>Les vergetures ?<\/h3>\n<p><strong>La peau<\/strong>\u00a0est\u00a0 le plus grand\u00a0<strong>organe<\/strong>\u00a0dans notre corps.\u00a0Il est divis\u00e9 en trois couches principales:<\/p>\n<ul>\n<li><strong>l&rsquo;hypoderme<\/strong>\u00a0&#8211; \u00e9galement connu sous le nom de tissu adipeux sous-cutan\u00e9, est la couche la plus profonde en contact avec les os et le cartilage;<\/li>\n<li><strong>derme<\/strong>\u00a0&#8211; la couche interm\u00e9diaire, tr\u00e8s vascularis\u00e9e et riche en collag\u00e8ne et en fibres du tissu conjonctif;<\/li>\n<li><strong>\u00e9piderme<\/strong>\u00a0&#8211; la couche \u00e9pith\u00e9liale de surface (compos\u00e9e de cinq couches de cellules et non vascularis\u00e9e).<\/li>\n<\/ul>\n<p>En d\u00e9pit d&rsquo;\u00eatre un organe incroyablement \u00e9lastique et durable, la peau a malheureusement des limites.\u00a0Si elle est soumise \u00e0 de fortes contraintes (telles qu&rsquo;une traction m\u00e9canique excessive) ou si elle est \u00e9tir\u00e9e au-del\u00e0 de ses limites d&rsquo;\u00e9lasticit\u00e9, la peau r\u00e9agit avec un processus divis\u00e9 en diff\u00e9rentes phases qui conduit \u00e0 la formation de vergetures.<\/p>\n<p>La premi\u00e8re est la\u00a0<strong>phase inflammatoire<\/strong>\u00a0(\u00a0<strong>ou\u00a0<\/strong><strong>hypertrophique<\/strong>\u00a0), dans laquelle le derme commence \u00e0 \u00eatre tir\u00e9 et soumis \u00e0 une surcharge. Cette inflammation affecte les\u00a0<strong>fibroblastes<\/strong>\u00a0, les cellules qui ont pour mission de produire du\u00a0<strong>collag\u00e8ne et de l&rsquo;\u00e9lastine. Cette phase provoque\u00a0<\/strong>une anomalie dans la production des prot\u00e9ines et dans le pire des cas l&rsquo;arr\u00eat du processus de production. En cons\u00e9quence, la structure et l&rsquo;\u00e9chafaudage du derme commencent \u00e0 subir des changements. A un certain instant, les premi\u00e8res fissures apparaissent. La phase inflammatoire est g\u00e9n\u00e9ralement asymptomatique en surface, mais\u00a0le patient\u00a0peut ressentir des br\u00fblures ou des d\u00e9mangeaisons dans les zones touch\u00e9es.<\/p>\n<p>La seconde est la\u00a0<strong>phase r\u00e9g\u00e9n\u00e9rative<\/strong>\u00a0, au cours de laquelle les fibroblastes reprennent leur processus de production mais le derme continue \u00e0\u00a0 \u00eatre trop tir\u00e9. Les fibres sont endommag\u00e9es et emm\u00eal\u00e9es,\u00a0de plus\u00a0les fibres de collag\u00e8ne sont cass\u00e9es. Par la suite, apparaissent des stries rouges ou roses (stries rubrae) sur la peau, commun\u00e9ment appel\u00e9es\u00a0<strong>vergetures rouges ou roses<\/strong>\u00a0. C&rsquo;est la phase o\u00f9 il est possible d&rsquo;intervenir efficacement aussi bien avec des processus cosm\u00e9tiques qu&rsquo;avec des traitements sp\u00e9cifiques.<\/p>\n<p>La derni\u00e8re est la\u00a0<strong>phase de gu\u00e9rison<\/strong>\u00a0qui est\u00a0a une dur\u00e9e variable.\u00a0De nouvelles fibres de collag\u00e8ne et d&rsquo;\u00e9lastine sont produits et la fissure du derme est gu\u00e9rie.\u00a0Les stries rouges deviennent\u00a0<strong>des vergetures blanches et nacr\u00e9es<\/strong>\u00a0(\u00a0<em>stries albae<\/em>\u00a0).\u00a0Dans cette phase, les vergetures ne peuvent \u00eatre trait\u00e9es, mais le processus de cicatrisation est irr\u00e9versible.<\/p>\n<h2>Causes des vergetures<\/h2>\n<p><strong>Les vergetures sont<\/strong>\u00a0en termes simples, le\u00a0<strong>r\u00e9sultat de la cicatrisation d&rsquo;une d\u00e9chirure du derme<\/strong>\u00a0.\u00a0Mais quels sont les facteurs \u00e0 l&rsquo;origine de cette d\u00e9chirure?<\/p>\n<p>Le premier est\u00a0<strong>l&rsquo;extension trop rapide de la peau<\/strong>\u00a0, comme cela se produit en cas de gains et de pertes de poids\u00a0 ou pendant la grossesse.\u00a0Dans ces cas, le derme passe d&rsquo;une condition normale \u00e0 une tension soudaine et constante qui provoque la d\u00e9gradation des fibres de collag\u00e8ne et d&rsquo;\u00e9lastine.\u00a0Dans ces circonstances, la zone la plus touch\u00e9e par les vergetures est le ventre mais il n&rsquo;est pas rare qu&rsquo;elles apparaissent \u00e9galement sur la poitrine et les cuisses.<\/p>\n<p>Les vergetures sont \u00e9galement de mauvaises marques laiss\u00e9es par la\u00a0<strong>pubert\u00e9<\/strong>\u00a0.\u00a0En effet, dans cette phase de d\u00e9veloppement, il peut arriver de passer par\u00a0<strong>des phases de croissance tr\u00e8s rapides<\/strong>\u00a0et que la peau ne dispose pas du temps et de l&rsquo;\u00e9lasticit\u00e9 n\u00e9cessaires pour s&rsquo;adapter au changement.<\/p>\n<h2>Comment traiter les vergetures<\/h2>\n<p><b>Il est impossible par le\u00a0traitement non invasif de faire dispara\u00eetre\u00a0totalement les vergetures.<\/b>\u00a0Tous les\u00a0traitements possibles restent des traitements partiellement efficaces qui ne forcent pas les vergetures \u00e0 ne pas se produire. Ce sont des traitements efficaces pour att\u00e9nuer la visibilit\u00e9 des vergetures. Avec une p\u00e9riode assez longue\u00a0apr\u00e8s leur apparition, il n&rsquo;est possible que de traiter les cicatrices des vergetures au laser. \u00a0Dans les cas de<strong>\u00a0peaux claires, un traitement au laser<\/strong>\u00a0est efficace \u00e0 r\u00e9duire le pr\u00e9judice esth\u00e9tique en stimulant la production de collag\u00e8ne.N\u00e9anmoins,\u00a0 Il est possible \u00e0 un stade inflammatoire, de traiter les vergetures au d\u00e9but lorsqu&rsquo;elles sont rouges violac\u00e9es .Les dermatologues et les m\u00e9decins sont tout \u00e0 fait d&rsquo;accord que c&rsquo;est\u00a0\u00e0 ce stade que les vergetures sont les plus\u00a0<strong>faciles \u00e0 \u00e9liminer<\/strong>.<\/p>\n<p align=\"justify\">Parmi les\u00a0<b>traitements\u00a0non invasifs propos\u00e9s par les chirurgiens\u00a0esth\u00e9tiques\u00a0et les dermatologues\u00a0<\/b>:<\/p>\n<ul>\n<li>Des\u00a0<strong>cr\u00e8mes \u00e0 base de\u00a0vitamine A<\/strong> \u00e0 appliquer sur les zones touch\u00e9es.<\/li>\n<li>L\u2019association des cr\u00e8mes \u00e0 base de vitamine A avec de l\u2019<strong>acide glycolique . <\/strong>Cette formule favorise la production de collag\u00e8ne pour encontrer les vergetures. Attention : Ces traitements sont uniquement\u00a0indiqu\u00e9s apr\u00e8s consultation directe et vous ne\u00a0\u00a0devez jamais acheter les m\u00e9dicaments sans ordonnance surtout pendant la grossesse.<\/li>\n<li>Les peaux claires, sont plus susceptibles \u00e0 \u00eatre trait\u00e9es par un\u00a0<strong>laser fractionn\u00e9<\/strong>\u00a0( <strong>CO2<\/strong>) , cette technique laser permet de <strong>lisser la peau<\/strong>\u00a0,\u00a0 <strong>booster la production des fibres du derme<\/strong>, et\u00a0<strong>r\u00e9g\u00e9n\u00e8re l&rsquo;\u00e9lastine<\/strong> par\u00a0une action thermique en profondeur.<\/li>\n<\/ul>\n<p align=\"justify\">\n","protected":false},"excerpt":{"rendered":"<p>Les\u00a0\u00a0vergetures\u00a0, connues sous le nom\u00a0striae distensae\u00a0en termes scientifiques, font partie des imperfections de la peau les plus courantes . Les vergetures peuvent se former sur la peau de n&rsquo;importe quelle personne, quel que soit le sexe, quelque soit l&rsquo;age\u00a0et quelque soit le type de la peau.\u00a0Les vergetures affectent les femmes environ deux fois de plus que les hommes . Elles sont des probl\u00e8mes typiques de l&rsquo;adolescence, de la grossesse ou des maladies pond\u00e9rales telles que l&rsquo;ob\u00e9sit\u00e9. les vergetures\u00a0sont \u00e9galement dues&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/\">Lire la suite<span class=\"screen-reader-text\"> Lire la suite<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1476,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,6],"tags":[],"class_list":["post-1471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-medecine-esthetique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vergetures : comment traiter les vergetures de la peau<\/title>\n<meta name=\"description\" content=\"Vergetures : les meilleures solutions pour traiter les vergetures de la peau, tout savoir sur les vergetures , la pr\u00e9vention et les rem\u00e8des.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vergetures : comment traiter les vergetures de la peau\" \/>\n<meta property=\"og:description\" content=\"Vergetures : les meilleures solutions pour traiter les vergetures de la peau, tout savoir sur les vergetures , la pr\u00e9vention et les rem\u00e8des.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-15T15:53:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-18T08:08:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2020\/07\/vergetures.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2121\" \/>\n\t<meta property=\"og:image:height\" content=\"1414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Espoir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Espoir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/comment-traiter-les-vergetures\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/comment-traiter-les-vergetures\\\/\"},\"author\":{\"name\":\"Espoir\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#\\\/schema\\\/person\\\/99909ac1fb9e3869cc198b6e24e174d7\"},\"headline\":\"Vergetures : comment les traiter ?\",\"datePublished\":\"2020-07-15T15:53:41+00:00\",\"dateModified\":\"2021-03-18T08:08:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/comment-traiter-les-vergetures\\\/\"},\"wordCount\":1042,\"image\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/comment-traiter-les-vergetures\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/vergetures.jpg\",\"articleSection\":[\"Blog\",\"M\u00e9decine esth\u00e9tique\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/comment-traiter-les-vergetures\\\/\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/comment-traiter-les-vergetures\\\/\",\"name\":\"Vergetures : comment traiter les vergetures de la peau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/comment-traiter-les-vergetures\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/comment-traiter-les-vergetures\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/vergetures.jpg\",\"datePublished\":\"2020-07-15T15:53:41+00:00\",\"dateModified\":\"2021-03-18T08:08:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#\\\/schema\\\/person\\\/99909ac1fb9e3869cc198b6e24e174d7\"},\"description\":\"Vergetures : les meilleures solutions pour traiter les vergetures de la peau, tout savoir sur les vergetures , la pr\u00e9vention et les rem\u00e8des.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/comment-traiter-les-vergetures\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/comment-traiter-les-vergetures\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/comment-traiter-les-vergetures\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/vergetures.jpg\",\"contentUrl\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/vergetures.jpg\",\"width\":2121,\"height\":1414,\"caption\":\"vergetures grossesse\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/comment-traiter-les-vergetures\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vergetures : comment les traiter ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/\",\"name\":\"Actualit\u00e9s\",\"description\":\"tout ce qui est en rapport avec la chirurgie esth\u00e9tique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#\\\/schema\\\/person\\\/99909ac1fb9e3869cc198b6e24e174d7\",\"name\":\"Espoir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2348b74ac1faeeba29af66f6ca25e9bce662a7e32d3a5f84df80788ea07d151f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2348b74ac1faeeba29af66f6ca25e9bce662a7e32d3a5f84df80788ea07d151f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2348b74ac1faeeba29af66f6ca25e9bce662a7e32d3a5f84df80788ea07d151f?s=96&d=mm&r=g\",\"caption\":\"Espoir\"},\"sameAs\":[\"http:\\\/\\\/www.medespoir.ch\"],\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/author\\\/espoir\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vergetures : comment traiter les vergetures de la peau","description":"Vergetures : les meilleures solutions pour traiter les vergetures de la peau, tout savoir sur les vergetures , la pr\u00e9vention et les rem\u00e8des.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/","og_locale":"fr_FR","og_type":"article","og_title":"Vergetures : comment traiter les vergetures de la peau","og_description":"Vergetures : les meilleures solutions pour traiter les vergetures de la peau, tout savoir sur les vergetures , la pr\u00e9vention et les rem\u00e8des.","og_url":"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/","og_site_name":"Actualit\u00e9s","article_published_time":"2020-07-15T15:53:41+00:00","article_modified_time":"2021-03-18T08:08:02+00:00","og_image":[{"width":2121,"height":1414,"url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2020\/07\/vergetures.jpg","type":"image\/jpeg"}],"author":"Espoir","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Espoir","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/#article","isPartOf":{"@id":"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/"},"author":{"name":"Espoir","@id":"https:\/\/www.medespoir.ch\/blog\/#\/schema\/person\/99909ac1fb9e3869cc198b6e24e174d7"},"headline":"Vergetures : comment les traiter ?","datePublished":"2020-07-15T15:53:41+00:00","dateModified":"2021-03-18T08:08:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/"},"wordCount":1042,"image":{"@id":"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/#primaryimage"},"thumbnailUrl":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2020\/07\/vergetures.jpg","articleSection":["Blog","M\u00e9decine esth\u00e9tique"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/","url":"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/","name":"Vergetures : comment traiter les vergetures de la peau","isPartOf":{"@id":"https:\/\/www.medespoir.ch\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/#primaryimage"},"image":{"@id":"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/#primaryimage"},"thumbnailUrl":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2020\/07\/vergetures.jpg","datePublished":"2020-07-15T15:53:41+00:00","dateModified":"2021-03-18T08:08:02+00:00","author":{"@id":"https:\/\/www.medespoir.ch\/blog\/#\/schema\/person\/99909ac1fb9e3869cc198b6e24e174d7"},"description":"Vergetures : les meilleures solutions pour traiter les vergetures de la peau, tout savoir sur les vergetures , la pr\u00e9vention et les rem\u00e8des.","breadcrumb":{"@id":"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/#primaryimage","url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2020\/07\/vergetures.jpg","contentUrl":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2020\/07\/vergetures.jpg","width":2121,"height":1414,"caption":"vergetures grossesse"},{"@type":"BreadcrumbList","@id":"https:\/\/www.medespoir.ch\/blog\/comment-traiter-les-vergetures\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.medespoir.ch\/blog\/"},{"@type":"ListItem","position":2,"name":"Vergetures : comment les traiter ?"}]},{"@type":"WebSite","@id":"https:\/\/www.medespoir.ch\/blog\/#website","url":"https:\/\/www.medespoir.ch\/blog\/","name":"Actualit\u00e9s","description":"tout ce qui est en rapport avec la chirurgie esth\u00e9tique","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medespoir.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.medespoir.ch\/blog\/#\/schema\/person\/99909ac1fb9e3869cc198b6e24e174d7","name":"Espoir","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2348b74ac1faeeba29af66f6ca25e9bce662a7e32d3a5f84df80788ea07d151f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2348b74ac1faeeba29af66f6ca25e9bce662a7e32d3a5f84df80788ea07d151f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2348b74ac1faeeba29af66f6ca25e9bce662a7e32d3a5f84df80788ea07d151f?s=96&d=mm&r=g","caption":"Espoir"},"sameAs":["http:\/\/www.medespoir.ch"],"url":"https:\/\/www.medespoir.ch\/blog\/author\/espoir\/"}]}},"_links":{"self":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts\/1471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/comments?post=1471"}],"version-history":[{"count":7,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts\/1471\/revisions"}],"predecessor-version":[{"id":1479,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts\/1471\/revisions\/1479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/media\/1476"}],"wp:attachment":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/media?parent=1471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/categories?post=1471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/tags?post=1471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}