{"id":1901,"date":"2021-04-19T16:22:28","date_gmt":"2021-04-19T14:22:28","guid":{"rendered":"https:\/\/www.medespoir.ch\/blog\/?p=1901"},"modified":"2021-04-20T16:37:24","modified_gmt":"2021-04-20T14:37:24","slug":"chirurgie-obesite-sleeve-gastrique","status":"publish","type":"post","link":"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/","title":{"rendered":"chirurgie ob\u00e9sit\u00e9 : l&rsquo;avantage de la Sleeve gastrectomie"},"content":{"rendered":"<p>Les patients souffrant de gastrectomie en manchon (<a href=\"https:\/\/www.medespoir.ch\/sleeve.php\">sleeve gastrectomie<\/a>) peuvent subir une perte de poids consid\u00e9rable, mais ils ont un risque r\u00e9duit de d\u00e9velopper certaines complications associ\u00e9es \u00e0 la chirurgie gastrique. Cette proc\u00e9dure laparoscopique est une chirurgie restrictive qui enl\u00e8ve environ 75 pour cent de l&rsquo;estomac. En plus de limiter la quantit\u00e9 de nourriture qu&rsquo;un patient peut consommer, cette r\u00e9duction de la taille de l&rsquo;estomac conduit le corps \u00e0 produire moins d&rsquo;hormones qui stimulent la faim. En cons\u00e9quence, les patients subissent souvent une suppression de l&rsquo;app\u00e9tit \u00e0 long terme. Au cours de la proc\u00e9dure de la sleeve gastrectomie, une partie verticale de l&rsquo;estomac est cr\u00e9\u00e9 \u00e0 l&rsquo;aide d&rsquo;un dispositif d&rsquo;agrafage. L&rsquo;estomac restant en forme et de la taille environ d&rsquo;une banane est plus long que la poche gastrique cr\u00e9\u00e9e lors d&rsquo;un bypass gastrique Roux-en-Y.<\/p>\n<p>&nbsp;<\/p>\n<h2>Avantages sleeve gastrectomie<\/h2>\n<p>&nbsp;<\/p>\n<p>Les patients s&rsquo;offrant une sleeve gastrectomie perdent de 50 \u00e0 83% de leur exc\u00e8s de poids dans les 12 \u00e0 24 mois qui suivent la chirurgie. Les risques sont minimes car les intestins ne sont pas contourn\u00e9s et le contournement ne concerne que l&rsquo;estomac. A c\u00f4t\u00e9 de l&rsquo;avantage de la r\u00e9duction chirurgicale de la taille, ce type de chirurgie fonctionne tr\u00e8s bien et le risque de certaines complications li\u00e9es au contournement gastrique est r\u00e9duit. Etant donn\u00e9 qu&rsquo;une partie importante de l&rsquo;estomac a \u00e9t\u00e9 retir\u00e9e, la production d&rsquo;hormones responsables de la stimulation de la faim est consid\u00e9rablement r\u00e9duite. Ce type de chirurgie r\u00e9duit l&rsquo;hormone de la faim et donne un sentiment de sati\u00e9t\u00e9 \u00e0 l&rsquo;ob\u00e8se. Par cons\u00e9quent, les patients se sentent rassasi\u00e9s plus rapidement avec une quantit\u00e9 de nourriture nettement inf\u00e9rieure. C&rsquo;est une intervention chirurgicale plus s\u00fbre ad\u00e9quate pour les patients \u00e0 haut risque. La sleeve gastrectomie est une solution pour les patients souffrant d&rsquo;affections qui les placent \u00e0 un risque \u00e9lev\u00e9 pour d&rsquo;autres formes de chirurgie bariatrique. Les patients peuvent entraver la perte de poids s&rsquo;ils n&rsquo;adoptent pas les changements alimentaires appropri\u00e9s apr\u00e8s la chirurgie. Les calories provenant d&rsquo;aliments comme la cr\u00e8me glac\u00e9e et les laits peuvent \u00eatre absorb\u00e9es et peuvent ralentir la perte de poids. Cette proc\u00e9dure n\u00e9cessite le retrait d&rsquo;une partie de l&rsquo;estomac et l&rsquo;agrafage du restant de la poche gastrique. Des complications peuvent survenir si une fuite se forme au niveau de la ligne d&rsquo;agrafage. Ce probl\u00e8me postop\u00e9ratoire s\u00e9v\u00e8re est trait\u00e9 avec des antibiotiques. De nombreux cas gu\u00e9rissent avec le temps. Cependant, la fuite peut \u00eatre suffisamment grave pour n\u00e9cessiter une intervention chirurgicale d&rsquo;urgence. Une partie de l&rsquo;estomac est d\u00e9finitivement \u00e9limin\u00e9e, Par cons\u00e9quent, cette chirurgie ne peut pas \u00eatre invers\u00e9e, bien qu&rsquo;elle puisse \u00eatre convertie en bypass gastrique et en interrupteur duod\u00e9nal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les patients souffrant de gastrectomie en manchon (sleeve gastrectomie) peuvent subir une perte de poids consid\u00e9rable, mais ils ont un risque r\u00e9duit de d\u00e9velopper certaines complications associ\u00e9es \u00e0 la chirurgie gastrique. Cette proc\u00e9dure laparoscopique est une chirurgie restrictive qui enl\u00e8ve environ 75 pour cent de l&rsquo;estomac. En plus de limiter la quantit\u00e9 de nourriture qu&rsquo;un patient peut consommer, cette r\u00e9duction de la taille de l&rsquo;estomac conduit le corps \u00e0 produire moins d&rsquo;hormones qui stimulent la faim. En cons\u00e9quence, les patients&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/\">Lire la suite<span class=\"screen-reader-text\"> Lire la suite<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":1903,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>chirurgie ob\u00e9sit\u00e9 : l&#039;avantage de la Sleeve gastrectomie<\/title>\n<meta name=\"description\" content=\"chirurgie ob\u00e9sit\u00e9 : avantage de la Sleeve gastrectomie ; l&#039;avantage du sleeve gastrectomie compar\u00e9 au bypass gastrique\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"chirurgie ob\u00e9sit\u00e9 : l&#039;avantage de la Sleeve gastrectomie\" \/>\n<meta property=\"og:description\" content=\"chirurgie ob\u00e9sit\u00e9 : avantage de la Sleeve gastrectomie ; l&#039;avantage du sleeve gastrectomie compar\u00e9 au bypass gastrique\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-19T14:22:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-20T14:37:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/04\/sleev.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"180\" \/>\n\t<meta property=\"og:image:height\" content=\"279\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Medespoir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Medespoir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgie-obesite-sleeve-gastrique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgie-obesite-sleeve-gastrique\\\/\"},\"author\":{\"name\":\"Medespoir\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#\\\/schema\\\/person\\\/f3137c0efad7e01f4f09954e4fe5fcaf\"},\"headline\":\"chirurgie ob\u00e9sit\u00e9 : l&rsquo;avantage de la Sleeve gastrectomie\",\"datePublished\":\"2021-04-19T14:22:28+00:00\",\"dateModified\":\"2021-04-20T14:37:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgie-obesite-sleeve-gastrique\\\/\"},\"wordCount\":475,\"image\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgie-obesite-sleeve-gastrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sleev.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgie-obesite-sleeve-gastrique\\\/\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgie-obesite-sleeve-gastrique\\\/\",\"name\":\"chirurgie ob\u00e9sit\u00e9 : l'avantage de la Sleeve gastrectomie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgie-obesite-sleeve-gastrique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgie-obesite-sleeve-gastrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sleev.jpg\",\"datePublished\":\"2021-04-19T14:22:28+00:00\",\"dateModified\":\"2021-04-20T14:37:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#\\\/schema\\\/person\\\/f3137c0efad7e01f4f09954e4fe5fcaf\"},\"description\":\"chirurgie ob\u00e9sit\u00e9 : avantage de la Sleeve gastrectomie ; l'avantage du sleeve gastrectomie compar\u00e9 au bypass gastrique\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgie-obesite-sleeve-gastrique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgie-obesite-sleeve-gastrique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgie-obesite-sleeve-gastrique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sleev.jpg\",\"contentUrl\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sleev.jpg\",\"width\":180,\"height\":279,\"caption\":\"avantages sleeve gastrectomie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgie-obesite-sleeve-gastrique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"chirurgie ob\u00e9sit\u00e9 : l&rsquo;avantage de la Sleeve gastrectomie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/\",\"name\":\"Actualit\u00e9s\",\"description\":\"tout ce qui est en rapport avec la chirurgie esth\u00e9tique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#\\\/schema\\\/person\\\/f3137c0efad7e01f4f09954e4fe5fcaf\",\"name\":\"Medespoir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g\",\"caption\":\"Medespoir\"},\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/author\\\/medespoir\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"chirurgie ob\u00e9sit\u00e9 : l'avantage de la Sleeve gastrectomie","description":"chirurgie ob\u00e9sit\u00e9 : avantage de la Sleeve gastrectomie ; l'avantage du sleeve gastrectomie compar\u00e9 au bypass gastrique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/","og_locale":"fr_FR","og_type":"article","og_title":"chirurgie ob\u00e9sit\u00e9 : l'avantage de la Sleeve gastrectomie","og_description":"chirurgie ob\u00e9sit\u00e9 : avantage de la Sleeve gastrectomie ; l'avantage du sleeve gastrectomie compar\u00e9 au bypass gastrique","og_url":"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/","og_site_name":"Actualit\u00e9s","article_published_time":"2021-04-19T14:22:28+00:00","article_modified_time":"2021-04-20T14:37:24+00:00","og_image":[{"width":180,"height":279,"url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/04\/sleev.jpg","type":"image\/jpeg"}],"author":"Medespoir","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Medespoir","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/#article","isPartOf":{"@id":"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/"},"author":{"name":"Medespoir","@id":"https:\/\/www.medespoir.ch\/blog\/#\/schema\/person\/f3137c0efad7e01f4f09954e4fe5fcaf"},"headline":"chirurgie ob\u00e9sit\u00e9 : l&rsquo;avantage de la Sleeve gastrectomie","datePublished":"2021-04-19T14:22:28+00:00","dateModified":"2021-04-20T14:37:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/"},"wordCount":475,"image":{"@id":"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/04\/sleev.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/","url":"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/","name":"chirurgie ob\u00e9sit\u00e9 : l'avantage de la Sleeve gastrectomie","isPartOf":{"@id":"https:\/\/www.medespoir.ch\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/#primaryimage"},"image":{"@id":"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/04\/sleev.jpg","datePublished":"2021-04-19T14:22:28+00:00","dateModified":"2021-04-20T14:37:24+00:00","author":{"@id":"https:\/\/www.medespoir.ch\/blog\/#\/schema\/person\/f3137c0efad7e01f4f09954e4fe5fcaf"},"description":"chirurgie ob\u00e9sit\u00e9 : avantage de la Sleeve gastrectomie ; l'avantage du sleeve gastrectomie compar\u00e9 au bypass gastrique","breadcrumb":{"@id":"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/#primaryimage","url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/04\/sleev.jpg","contentUrl":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/04\/sleev.jpg","width":180,"height":279,"caption":"avantages sleeve gastrectomie"},{"@type":"BreadcrumbList","@id":"https:\/\/www.medespoir.ch\/blog\/chirurgie-obesite-sleeve-gastrique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.medespoir.ch\/blog\/"},{"@type":"ListItem","position":2,"name":"chirurgie ob\u00e9sit\u00e9 : l&rsquo;avantage de la Sleeve gastrectomie"}]},{"@type":"WebSite","@id":"https:\/\/www.medespoir.ch\/blog\/#website","url":"https:\/\/www.medespoir.ch\/blog\/","name":"Actualit\u00e9s","description":"tout ce qui est en rapport avec la chirurgie esth\u00e9tique","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medespoir.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.medespoir.ch\/blog\/#\/schema\/person\/f3137c0efad7e01f4f09954e4fe5fcaf","name":"Medespoir","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g","caption":"Medespoir"},"url":"https:\/\/www.medespoir.ch\/blog\/author\/medespoir\/"}]}},"_links":{"self":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts\/1901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/comments?post=1901"}],"version-history":[{"count":2,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts\/1901\/revisions"}],"predecessor-version":[{"id":1904,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts\/1901\/revisions\/1904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/media\/1903"}],"wp:attachment":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/media?parent=1901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/categories?post=1901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/tags?post=1901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}