{"id":2387,"date":"2021-10-06T15:30:32","date_gmt":"2021-10-06T13:30:32","guid":{"rendered":"https:\/\/www.medespoir.ch\/blog\/?p=2387"},"modified":"2021-10-06T17:58:16","modified_gmt":"2021-10-06T15:58:16","slug":"tumorectomie-correction-sein","status":"publish","type":"post","link":"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/","title":{"rendered":"Techniques de tumorectomie oncoplastique pour corriger les seins"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Retirer le tissu mammaire contenant le cancer et combiner cette op\u00e9ration avec une <a href=\"https:\/\/www.medespoir.ch\/reduction-mammaire.php\">r\u00e9duction mammaire<\/a>, un lifting des seins, ou les deux. Si n\u00e9cessaire, le chirurgien peut apporter des ajustements \u00e0 l&rsquo;autre sein pour cr\u00e9er une apparence \u00e9quilibr\u00e9e.<\/p>\n<p>&nbsp;<\/p>\n<p>Bien que la chirurgie oncoplastique soit utilis\u00e9e en Europe et en Am\u00e9rique latine depuis une grande p\u00e9riode, Cette chirurgie est devenue plus courante au monde, en particulier depuis le d\u00e9but des ann\u00e9es 2010. Si vous \u00eates un bon candidat \u00e0 une tumorectomie, vous voudrez peut-\u00eatre demander \u00e0 votre chirurgien d&rsquo;utiliser une approche oncoplastique.<\/p>\n<h2><\/h2>\n<h2><\/h2>\n<h2>Succ\u00e8s de la tumorectomie oncoplastique ?<\/h2>\n<p>&nbsp;<\/p>\n<p>Prendre des d\u00e9cisions concernant la tumorectomie oncoplastique et coop\u00e9rer avec un chirurgien oncoplastique\/une \u00e9quipe chirurgicale vous garantit le succ\u00e8s de l&rsquo;op\u00e9ration.<\/p>\n<p>&nbsp;<\/p>\n<h2>Tumorectomie oncoplastique : une reconstruction seins ?<\/h2>\n<p>&nbsp;<\/p>\n<p>Les deux principales options pour la chirurgie du cancer du sein sont la tumorectomie et la mastectomie. La reconstruction mammaire est syst\u00e9matiquement propos\u00e9e avec la mastectomie, mais vous ne savez peut-\u00eatre pas que la chirurgie oncoplastique pourrait \u00eatre une option de reconstruction mammaire.<\/p>\n<p>&nbsp;<\/p>\n<h2><\/h2>\n<h2>Tumorectomie classique vs chirurgie oncoplastique : quelles diff\u00e9rences ?<\/h2>\n<p>&nbsp;<\/p>\n<p>La tumorectomie \u00e9galement appel\u00e9e mastectomie partielle ou chirurgie mammaire conservatrice enl\u00e8ve le cancer du sein et un bord de tissu sain appel\u00e9 marge, pr\u00e9servant la majeure partie du sein. Le chirurgien referme ensuite l&rsquo;incision, au fil du temps, du liquide remplit l&rsquo;espace o\u00f9 le cancer a \u00e9t\u00e9 retir\u00e9 (c&rsquo;est ce qu&rsquo;on appelle un s\u00e9rome).<\/p>\n<p>&nbsp;<\/p>\n<p>Si le cancer est de taille plus petite, dans un endroit pas tr\u00e8s \u00e9vident et que vous avez des seins plus gros ou de taille moyenne, vous pouvez avoir un r\u00e9sultat esth\u00e9tique qui vous convient apr\u00e8s une tumorectomie.<\/p>\n<p>&nbsp;<\/p>\n<p>Dans certains cas, une bosse se forme et provoque une indentation visible dans la poitrine, une cicatrice serr\u00e9e qui cause des distorsions dans l&rsquo;apparence du mamelon. Toute radioth\u00e9rapie administr\u00e9e apr\u00e8s une tumorectomie peut aggraver l&rsquo;apparence du sein et peut \u00e9galement affecter la taille et la forme du sein trait\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p>La tumorectomie oncoplastique combine des techniques de chirurgie plastique avec une tumorectomie pour \u00e0 la fois retirer le cancer et reconstruire et remodeler le sein. Il peut \u00eatre utile pour obtenir de bons r\u00e9sultats esth\u00e9tiques chez de nombreuses femmes qui choisissent la tumorectomie, telles que celles qui ont :<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Seins plus petits, o\u00f9 l&rsquo;ablation m\u00eame d&rsquo;une petite tumeur est susceptible d&rsquo;avoir un impact visible<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Cancer du sein dans un endroit particuli\u00e8rement visible, comme haut sur la paroi thoracique, sur la partie interne du sein ou pr\u00e8s du mamelon<\/li>\n<li>Seins de taille moyenne \u00e0 grande et n\u00e9cessit\u00e9 de retirer une grande quantit\u00e9 de tissu (20 \u00e0 50 %) du sein affect\u00e9<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Chimioth\u00e9rapie avant la chirurgie (appel\u00e9e chimioth\u00e9rapie n\u00e9oadjuvante) qui r\u00e9tr\u00e9cit suffisamment le cancer pour rendre possible la tumorectomie probl\u00e8mes existants avec leurs seins, tels qu&rsquo;un affaissement excessif (ptosis), une tr\u00e8s grande taille (macromastie) ou un manque \u00e9vident de sym\u00e9trie (\u00e9quilibre), qui pourraient \u00eatre trait\u00e9s en m\u00eame temps ou moment o\u00f9 le cancer est retir\u00e9<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>La tumorectomie oncoplastique n&rsquo;est pas une bonne option pour le cancer du sein inflammatoire ou pour les cancers qui ne peuvent pas \u00eatre compl\u00e8tement \u00e9limin\u00e9s avec un bon r\u00e9sultat esth\u00e9tique. L&rsquo;op\u00e9ration peut \u00e9galement ne pas \u00eatre possible s&rsquo;il y a plusieurs tumeurs dans le sein, \u00e0 moins que le sein ne soit assez gros.<\/p>\n<h2><\/h2>\n<h2>Techniques de tumorectomie oncoplastique<\/h2>\n<p>&nbsp;<\/p>\n<p>Il existe de nombreuses approches pour la tumorectomie oncoplastique. On les classe en niveau 1 ou niveau 2, selon leur complexit\u00e9. Avec toutes ces approches, le chirurgien fait attention \u00e0 la position du mamelon et \u00e0 la position de l&rsquo;ar\u00e9ole, ajustant son emplacement au besoin tout en maintenant son approvisionnement en sang.<\/p>\n<h2><\/h2>\n<h2>Les op\u00e9rations esth\u00e9tiques garantissent<\/h2>\n<p>&nbsp;<\/p>\n<p>D\u00e9placement du volume : Il s&rsquo;agit d&rsquo;un r\u00e9arrangement et placement esth\u00e9tique de la cicatrice, cette op\u00e9ration modifie la forme du sein. Le chirurgien enl\u00e8ve d&rsquo;abord le cancer et une partie du tissu touch\u00e9. Le chirurgien d\u00e9tache le tissu voisin sous la peau du sein et l&rsquo;utilise pour combler l&rsquo;espace laiss\u00e9. Le chirurgien peut cacher la cicatrice en la pla\u00e7ant sous le bras(axillaire), autour de l&rsquo;ar\u00e9ole ou dans la zone sous le sein (le pli sous-mammaire).<\/p>\n<p>&nbsp;<\/p>\n<p>Il existe de nombreux types d&rsquo;incisions qu&rsquo;un chirurgien peut utiliser, en fonction de l&#8217;emplacement de la tumeur. En r\u00e8gle g\u00e9n\u00e9rale, les chirurgiens du sein et les chirurgiens g\u00e9n\u00e9ralistes qui traitent fr\u00e9quemment le cancer du sein sont en mesure d&rsquo;effectuer des proc\u00e9dures de niveau 1.<\/p>\n<p>&nbsp;<\/p>\n<p>Les op\u00e9rations de niveau 2 comprennent :<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>R\u00e9duction de volume avec lifting des seins (mastopexie) : Le chirurgien retire la partie du sein qui contient le cancer puis effectue un lifting des seins. Cette proc\u00e9dure peut traiter les seins affaiss\u00e9s (ptosis) ou l&rsquo;exc\u00e8s de peau. Pour rendre les seins sym\u00e9triques, le chirurgien peut \u00e9galement effectuer un lifting des seins de l&rsquo;autre c\u00f4t\u00e9.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>R\u00e9duction mammaire significative (plastie mammaire de r\u00e9duction) : Si une femme a de tr\u00e8s gros seins, le chirurgien peut retirer le cancer et une plus grande quantit\u00e9 de tissu environnant dans le cadre d&rsquo;une r\u00e9duction mammaire. Le chirurgien r\u00e9duirait \u00e9galement la taille de l&rsquo;autre sein pour correspondre.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Remplacement du volume \u00e0 l&rsquo;aide de lambeaux de tissu \u00e0 proximit\u00e9 : les lambeaux de tissu du c\u00f4t\u00e9 du corps (pr\u00e8s du sein) ou du haut du dos peuvent \u00eatre d\u00e9plac\u00e9s dans la r\u00e9gion du sein tout en restant attach\u00e9s \u00e0 leur irrigation sanguine (c&rsquo;est ce qu&rsquo;on appelle un lambeau p\u00e9dicul\u00e9). Le chirurgien peut utiliser des lambeaux s&rsquo;il n&rsquo;y a pas assez de tissu \u00e0 proximit\u00e9 pour combler l&rsquo;espace laiss\u00e9 apr\u00e8s la tumorectomie (chez une femme aux seins plus petits, par exemple) ou si une femme souhaite maintenir la taille de sa poitrine.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Remplacement du volume avec greffe de graisse : les chirurgiens peuvent utiliser cette technique plus tard, apr\u00e8s la fin de la radioth\u00e9rapie, pour combler les zones du sein au besoin ou pour s&rsquo;assurer que les seins sont sym\u00e9triques (\u00e9quilibr\u00e9s).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Les op\u00e9rations de niveau 2 n\u00e9cessitent un chirurgien plasticien travaillant en collaboration avec le chirurgien canc\u00e9rologue. Cependant, les liftings et r\u00e9ductions mammaires oncoplastiques peuvent \u00e9galement \u00eatre effectu\u00e9s par des chirurgiens du cancer du sein ayant une formation et une exp\u00e9rience approfondies des techniques oncoplastiques. Les lambeaux et la greffe de graisse n\u00e9cessitent un chirurgien plasticien.<\/p>\n<p>&nbsp;<\/p>\n<p>Tous les chirurgiens que vous envisagez doivent \u00eatre en mesure de d\u00e9montrer qu&rsquo;ils ont effectu\u00e9 bon nombre de ces op\u00e9rations dans le pass\u00e9, avec de bons r\u00e9sultats et un dossier de s\u00e9curit\u00e9 \u00e9tabli.<\/p>\n<p>&nbsp;<\/p>\n<p>Autres informations \u00e0 savoir sur la tumorectomie oncoplastique<\/p>\n<p>Comme pour une tumorectomie ordinaire, le chirurgien effectuant une tumorectomie oncoplastique envoie le cancer retir\u00e9 pour des tests de pathologie. Le pathologiste s&rsquo;assure que le chirurgien a obtenu des marges nettes ou n\u00e9gatives. Lorsque les marges sont n\u00e9gatives, cela signifie qu&rsquo;aucun cancer n&rsquo;est pr\u00e9sent sur les bords du tissu sain que le chirurgien a retir\u00e9 avec le cancer. Lorsque les marges sont positives, cela signifie que le cancer est pr\u00e9sent sur les bords du tissu sain retir\u00e9 et qu&rsquo;une autre intervention chirurgicale est n\u00e9cessaire pour retirer plus de tissu. Les marges positives sont moins pr\u00e9occupantes si vous subissez une r\u00e9duction mammaire importante, qui \u00e9limine une quantit\u00e9 beaucoup plus importante de tissus en m\u00eame temps que le cancer.<\/p>\n<p>&nbsp;<\/p>\n<p>Les chirurgiens qui r\u00e9arrangent le tissu mammaire pour combler l&rsquo;espace laiss\u00e9 apr\u00e8s l&rsquo;ablation du cancer doivent marquer le site de la tumeur d&rsquo;origine. Ils peuvent utiliser des clips m\u00e9talliques ; une suture radio-opaque flexible (un type de suture permanente visible sur les radiographies); ou un marqueur \u00ab bio absorbable \u00bb (un petit dispositif en forme de spirale qui se dissout avec le temps mais laisse les clips de fa\u00e7on permanente). Ces dispositifs garantissent que, m\u00eame apr\u00e8s l\u2019ablation du tissu mammaire, vos chirurgiens et m\u00e9decins sont toujours en mesure de voir l&#8217;emplacement d&rsquo;origine du cancer. Ceci est utile pour planifier les traitements de radioth\u00e9rapie et pour les futurs d\u00e9pistages du cancer du sein. C&rsquo;est \u00e9galement important dans le petit pourcentage o\u00f9 le pathologiste trouve des tests de r\u00e9cidives positives.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Retirer le tissu mammaire contenant le cancer et combiner cette op\u00e9ration avec une r\u00e9duction mammaire, un lifting des seins, ou les deux. Si n\u00e9cessaire, le chirurgien peut apporter des ajustements \u00e0 l&rsquo;autre sein pour cr\u00e9er une apparence \u00e9quilibr\u00e9e. &nbsp; Bien que la chirurgie oncoplastique soit utilis\u00e9e en Europe et en Am\u00e9rique latine depuis une grande p\u00e9riode, Cette chirurgie est devenue plus courante au monde, en particulier depuis le d\u00e9but des ann\u00e9es 2010. Si vous \u00eates un bon candidat \u00e0&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/\">Lire la suite<span class=\"screen-reader-text\"> Lire la suite<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":2391,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tumorectomie classique vs chirurgie oncoplastique<\/title>\n<meta name=\"description\" content=\"Tumorectomie classique vs chirurgie oncoplastique : quelles diff\u00e9rences entre deux types chirurgie reconstruction mammaire, tumeroctomie Tunis\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tumorectomie classique vs chirurgie oncoplastique\" \/>\n<meta property=\"og:description\" content=\"Tumorectomie classique vs chirurgie oncoplastique : quelles diff\u00e9rences entre deux types chirurgie reconstruction mammaire, tumeroctomie Tunis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-06T13:30:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-06T15:58:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/10\/correction-seins-tunis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"638\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Medespoir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Medespoir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/tumorectomie-correction-sein\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/tumorectomie-correction-sein\\\/\"},\"author\":{\"name\":\"Medespoir\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#\\\/schema\\\/person\\\/f3137c0efad7e01f4f09954e4fe5fcaf\"},\"headline\":\"Techniques de tumorectomie oncoplastique pour corriger les seins\",\"datePublished\":\"2021-10-06T13:30:32+00:00\",\"dateModified\":\"2021-10-06T15:58:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/tumorectomie-correction-sein\\\/\"},\"wordCount\":1420,\"image\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/tumorectomie-correction-sein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/correction-seins-tunis.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/tumorectomie-correction-sein\\\/\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/tumorectomie-correction-sein\\\/\",\"name\":\"Tumorectomie classique vs chirurgie oncoplastique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/tumorectomie-correction-sein\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/tumorectomie-correction-sein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/correction-seins-tunis.jpg\",\"datePublished\":\"2021-10-06T13:30:32+00:00\",\"dateModified\":\"2021-10-06T15:58:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#\\\/schema\\\/person\\\/f3137c0efad7e01f4f09954e4fe5fcaf\"},\"description\":\"Tumorectomie classique vs chirurgie oncoplastique : quelles diff\u00e9rences entre deux types chirurgie reconstruction mammaire, tumeroctomie Tunis\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/tumorectomie-correction-sein\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/tumorectomie-correction-sein\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/tumorectomie-correction-sein\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/correction-seins-tunis.jpg\",\"contentUrl\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/correction-seins-tunis.jpg\",\"width\":638,\"height\":570,\"caption\":\"correction seins Tunis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/tumorectomie-correction-sein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Techniques de tumorectomie oncoplastique pour corriger les seins\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/\",\"name\":\"Actualit\u00e9s\",\"description\":\"tout ce qui est en rapport avec la chirurgie esth\u00e9tique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#\\\/schema\\\/person\\\/f3137c0efad7e01f4f09954e4fe5fcaf\",\"name\":\"Medespoir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g\",\"caption\":\"Medespoir\"},\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/author\\\/medespoir\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tumorectomie classique vs chirurgie oncoplastique","description":"Tumorectomie classique vs chirurgie oncoplastique : quelles diff\u00e9rences entre deux types chirurgie reconstruction mammaire, tumeroctomie Tunis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/","og_locale":"fr_FR","og_type":"article","og_title":"Tumorectomie classique vs chirurgie oncoplastique","og_description":"Tumorectomie classique vs chirurgie oncoplastique : quelles diff\u00e9rences entre deux types chirurgie reconstruction mammaire, tumeroctomie Tunis","og_url":"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/","og_site_name":"Actualit\u00e9s","article_published_time":"2021-10-06T13:30:32+00:00","article_modified_time":"2021-10-06T15:58:16+00:00","og_image":[{"width":638,"height":570,"url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/10\/correction-seins-tunis.jpg","type":"image\/jpeg"}],"author":"Medespoir","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Medespoir","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/#article","isPartOf":{"@id":"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/"},"author":{"name":"Medespoir","@id":"https:\/\/www.medespoir.ch\/blog\/#\/schema\/person\/f3137c0efad7e01f4f09954e4fe5fcaf"},"headline":"Techniques de tumorectomie oncoplastique pour corriger les seins","datePublished":"2021-10-06T13:30:32+00:00","dateModified":"2021-10-06T15:58:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/"},"wordCount":1420,"image":{"@id":"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/10\/correction-seins-tunis.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/","url":"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/","name":"Tumorectomie classique vs chirurgie oncoplastique","isPartOf":{"@id":"https:\/\/www.medespoir.ch\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/#primaryimage"},"image":{"@id":"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/10\/correction-seins-tunis.jpg","datePublished":"2021-10-06T13:30:32+00:00","dateModified":"2021-10-06T15:58:16+00:00","author":{"@id":"https:\/\/www.medespoir.ch\/blog\/#\/schema\/person\/f3137c0efad7e01f4f09954e4fe5fcaf"},"description":"Tumorectomie classique vs chirurgie oncoplastique : quelles diff\u00e9rences entre deux types chirurgie reconstruction mammaire, tumeroctomie Tunis","breadcrumb":{"@id":"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/#primaryimage","url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/10\/correction-seins-tunis.jpg","contentUrl":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/10\/correction-seins-tunis.jpg","width":638,"height":570,"caption":"correction seins Tunis"},{"@type":"BreadcrumbList","@id":"https:\/\/www.medespoir.ch\/blog\/tumorectomie-correction-sein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.medespoir.ch\/blog\/"},{"@type":"ListItem","position":2,"name":"Techniques de tumorectomie oncoplastique pour corriger les seins"}]},{"@type":"WebSite","@id":"https:\/\/www.medespoir.ch\/blog\/#website","url":"https:\/\/www.medespoir.ch\/blog\/","name":"Actualit\u00e9s","description":"tout ce qui est en rapport avec la chirurgie esth\u00e9tique","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medespoir.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.medespoir.ch\/blog\/#\/schema\/person\/f3137c0efad7e01f4f09954e4fe5fcaf","name":"Medespoir","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g","caption":"Medespoir"},"url":"https:\/\/www.medespoir.ch\/blog\/author\/medespoir\/"}]}},"_links":{"self":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts\/2387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/comments?post=2387"}],"version-history":[{"count":6,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts\/2387\/revisions"}],"predecessor-version":[{"id":2394,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts\/2387\/revisions\/2394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/media\/2391"}],"wp:attachment":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/media?parent=2387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/categories?post=2387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/tags?post=2387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}