{"id":2514,"date":"2021-11-08T11:11:41","date_gmt":"2021-11-08T10:11:41","guid":{"rendered":"https:\/\/www.medespoir.ch\/blog\/?p=2514"},"modified":"2021-11-08T11:48:33","modified_gmt":"2021-11-08T10:48:33","slug":"chirurgies-remodelage-du-corps","status":"publish","type":"post","link":"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/","title":{"rendered":"Chirurgie du remodelage du corps"},"content":{"rendered":"<p>Suite \u00e0 une grossesse, une perte de poids importante comme suite au vieillissement, les personnes peuvent se retrouver avec un exc\u00e8s de peau, des vergetures, des zones d&rsquo;exc\u00e8s de graisse ou un d\u00e9s\u00e9quilibre du contour abdominal. Les op\u00e9rations de remodelage du corps peuvent aider \u00e0 r\u00e9soudre ce probl\u00e8me notamment :<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Abdominoplastie (plastie abdominale)<\/strong> : enl\u00e8ve le tablier de peau suppl\u00e9mentaire sur l&rsquo;abdomen et, lorsque cela est indiqu\u00e9, comprend \u00e9galement l&rsquo;\u00e9limination de l&rsquo;exc\u00e8s de graisse et la r\u00e9paration des muscles abdominaux endommag\u00e9s.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Lifting du corps :<\/strong> enl\u00e8ve la peau autour de toute la taille pour soulever les fesses, les cuisses lat\u00e9rales et couper le ventre.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Lifting des bras (brachioplastie)<\/strong>: enl\u00e8ve la peau suppl\u00e9mentaire de la partie sup\u00e9rieure des bras<\/li>\n<li><strong>Lifting cuisses :<\/strong> \u00e9limine l&rsquo;exc\u00e8s de peau des cuisses<\/li>\n<\/ul>\n<h2><\/h2>\n<h2>Chirurgie du remodelage du corps<\/h2>\n<p>&nbsp;<\/p>\n<p>La chirurgie de remodelage du corps est con\u00e7ue pour resserrer la peau l\u00e2che et flasque. Cette chirurgie modifie la texture de la peau en l&rsquo;\u00e9tirant, rendant ainsi le rel\u00e2chement et les rides moins apparents.<\/p>\n<p>&nbsp;<\/p>\n<p>La chirurgie de remodelage du corps peut \u00eatre associ\u00e9e \u00e0 une liposuccion, Celle-ci est con\u00e7ue pour am\u00e9liorer les d\u00e9p\u00f4ts graisseux, et non pour resserrer la peau l\u00e2che. La liposuccion seule peut aggraver l&rsquo;apparence de la peau chez les patients pr\u00e9sentant une faible \u00e9lasticit\u00e9 de la peau.<\/p>\n<p>&nbsp;<\/p>\n<p>Comme pour la liposuccion, la chirurgie de remodelage corporel n&rsquo;est pas destin\u00e9e \u00e0 corriger l&rsquo;ob\u00e9sit\u00e9 ; les patients doivent avoir un poids normal ou proche de la normale au moment de la chirurgie.<\/p>\n<h2>D\u00e9roulement et cicatrisation<\/h2>\n<p>La plupart des op\u00e9rations de remodelage corporel sont effectu\u00e9es sous anesth\u00e9sie g\u00e9n\u00e9rale. La peau flasque ne peut pas \u00eatre enlev\u00e9e sans laisser de cicatrices, et le contour du corps signifie souvent de longues incisions qui entra\u00eenent de longues cicatrices. Votre chirurgien plasticien mettra tout en \u0153uvre pour vous donner les meilleures cicatrices possibles, et les dissimuler dans les zones les moins visibles.<\/p>\n<p>&nbsp;<\/p>\n<p>Votre chirurgien vous indiquera lors de votre consultation sur les options qui garantissent une cicatrice minimale. Bien que les cicatrices s&rsquo;estompent avec le temps, les cicatrices seront permanentes dans leur largeur, leur hauteur et leur couleur finale.<\/p>\n<h2><\/h2>\n<h2>R\u00e9cup\u00e9ration et complications possibles<\/h2>\n<p>&nbsp;<\/p>\n<p>Les complications les plus courantes de la chirurgie de remodelage corporel sont :<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>H\u00e9matome (accumulation de sang sous la peau)<\/li>\n<li>s\u00e9rome (accumulation de liquide sous la peau)<\/li>\n<li>Engourdissement de la peau<\/li>\n<\/ul>\n<p>Alors que la plupart des sensations reviennent g\u00e9n\u00e9ralement, l&rsquo;h\u00e9matome et le s\u00e9rome peuvent n\u00e9cessiter une intervention pour drainer le sang ou le s\u00e9rum qui s&rsquo;est accumul\u00e9. Des probl\u00e8mes de cicatrisation apr\u00e8s la chirurgie sont \u00e9galement possibles, notamment pour les fumeurs.<\/p>\n<p>&nbsp;<\/p>\n<p>Les activit\u00e9s normales peuvent g\u00e9n\u00e9ralement \u00eatre reprises en quelques semaines et de nombreuses personnes retournent au travail la troisi\u00e8me semaine apr\u00e8s la chirurgie. Cela peut prendre 6 \u00e0 12 mois pour voir le r\u00e9sultat final de la chirurgie de remodelage du corps.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Suite \u00e0 une grossesse, une perte de poids importante comme suite au vieillissement, les personnes peuvent se retrouver avec un exc\u00e8s de peau, des vergetures, des zones d&rsquo;exc\u00e8s de graisse ou un d\u00e9s\u00e9quilibre du contour abdominal. Les op\u00e9rations de remodelage du corps peuvent aider \u00e0 r\u00e9soudre ce probl\u00e8me notamment : &nbsp; Abdominoplastie (plastie abdominale) : enl\u00e8ve le tablier de peau suppl\u00e9mentaire sur l&rsquo;abdomen et, lorsque cela est indiqu\u00e9, comprend \u00e9galement l&rsquo;\u00e9limination de l&rsquo;exc\u00e8s de graisse et la r\u00e9paration des muscles&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/\">Lire la suite<span class=\"screen-reader-text\"> Lire la suite<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":2516,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chirurgie du remodelage du corps : comment lifter le corps<\/title>\n<meta name=\"description\" content=\"Chirurgie du remodelage du corps : Tout savoir sur la chirurgie de remodelage du corps, remodelage corporel tout compris\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chirurgie du remodelage du corps : comment lifter le corps\" \/>\n<meta property=\"og:description\" content=\"Chirurgie du remodelage du corps : Tout savoir sur la chirurgie de remodelage du corps, remodelage corporel tout compris\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-08T10:11:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-08T10:48:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/11\/remodelage-corps.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Medespoir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Medespoir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgies-remodelage-du-corps\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgies-remodelage-du-corps\\\/\"},\"author\":{\"name\":\"Medespoir\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#\\\/schema\\\/person\\\/f3137c0efad7e01f4f09954e4fe5fcaf\"},\"headline\":\"Chirurgie du remodelage du corps\",\"datePublished\":\"2021-11-08T10:11:41+00:00\",\"dateModified\":\"2021-11-08T10:48:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgies-remodelage-du-corps\\\/\"},\"wordCount\":524,\"image\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgies-remodelage-du-corps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/remodelage-corps.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgies-remodelage-du-corps\\\/\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgies-remodelage-du-corps\\\/\",\"name\":\"Chirurgie du remodelage du corps : comment lifter le corps\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgies-remodelage-du-corps\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgies-remodelage-du-corps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/remodelage-corps.jpg\",\"datePublished\":\"2021-11-08T10:11:41+00:00\",\"dateModified\":\"2021-11-08T10:48:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#\\\/schema\\\/person\\\/f3137c0efad7e01f4f09954e4fe5fcaf\"},\"description\":\"Chirurgie du remodelage du corps : Tout savoir sur la chirurgie de remodelage du corps, remodelage corporel tout compris\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgies-remodelage-du-corps\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgies-remodelage-du-corps\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgies-remodelage-du-corps\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/remodelage-corps.jpg\",\"contentUrl\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/remodelage-corps.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"remodelage corps\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/chirurgies-remodelage-du-corps\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chirurgie du remodelage du corps\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/\",\"name\":\"Actualit\u00e9s\",\"description\":\"tout ce qui est en rapport avec la chirurgie esth\u00e9tique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/#\\\/schema\\\/person\\\/f3137c0efad7e01f4f09954e4fe5fcaf\",\"name\":\"Medespoir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g\",\"caption\":\"Medespoir\"},\"url\":\"https:\\\/\\\/www.medespoir.ch\\\/blog\\\/author\\\/medespoir\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chirurgie du remodelage du corps : comment lifter le corps","description":"Chirurgie du remodelage du corps : Tout savoir sur la chirurgie de remodelage du corps, remodelage corporel tout compris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/","og_locale":"fr_FR","og_type":"article","og_title":"Chirurgie du remodelage du corps : comment lifter le corps","og_description":"Chirurgie du remodelage du corps : Tout savoir sur la chirurgie de remodelage du corps, remodelage corporel tout compris","og_url":"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/","og_site_name":"Actualit\u00e9s","article_published_time":"2021-11-08T10:11:41+00:00","article_modified_time":"2021-11-08T10:48:33+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/11\/remodelage-corps.jpg","type":"image\/jpeg"}],"author":"Medespoir","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Medespoir","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/#article","isPartOf":{"@id":"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/"},"author":{"name":"Medespoir","@id":"https:\/\/www.medespoir.ch\/blog\/#\/schema\/person\/f3137c0efad7e01f4f09954e4fe5fcaf"},"headline":"Chirurgie du remodelage du corps","datePublished":"2021-11-08T10:11:41+00:00","dateModified":"2021-11-08T10:48:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/"},"wordCount":524,"image":{"@id":"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/#primaryimage"},"thumbnailUrl":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/11\/remodelage-corps.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/","url":"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/","name":"Chirurgie du remodelage du corps : comment lifter le corps","isPartOf":{"@id":"https:\/\/www.medespoir.ch\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/#primaryimage"},"image":{"@id":"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/#primaryimage"},"thumbnailUrl":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/11\/remodelage-corps.jpg","datePublished":"2021-11-08T10:11:41+00:00","dateModified":"2021-11-08T10:48:33+00:00","author":{"@id":"https:\/\/www.medespoir.ch\/blog\/#\/schema\/person\/f3137c0efad7e01f4f09954e4fe5fcaf"},"description":"Chirurgie du remodelage du corps : Tout savoir sur la chirurgie de remodelage du corps, remodelage corporel tout compris","breadcrumb":{"@id":"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/#primaryimage","url":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/11\/remodelage-corps.jpg","contentUrl":"https:\/\/www.medespoir.ch\/blog\/wp-content\/uploads\/2021\/11\/remodelage-corps.jpg","width":2000,"height":1333,"caption":"remodelage corps"},{"@type":"BreadcrumbList","@id":"https:\/\/www.medespoir.ch\/blog\/chirurgies-remodelage-du-corps\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.medespoir.ch\/blog\/"},{"@type":"ListItem","position":2,"name":"Chirurgie du remodelage du corps"}]},{"@type":"WebSite","@id":"https:\/\/www.medespoir.ch\/blog\/#website","url":"https:\/\/www.medespoir.ch\/blog\/","name":"Actualit\u00e9s","description":"tout ce qui est en rapport avec la chirurgie esth\u00e9tique","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medespoir.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.medespoir.ch\/blog\/#\/schema\/person\/f3137c0efad7e01f4f09954e4fe5fcaf","name":"Medespoir","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2749d49026cb64198c0ffdb8c6cf892efeb307abed9491ae51e487581fb6383b?s=96&d=mm&r=g","caption":"Medespoir"},"url":"https:\/\/www.medespoir.ch\/blog\/author\/medespoir\/"}]}},"_links":{"self":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts\/2514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/comments?post=2514"}],"version-history":[{"count":1,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts\/2514\/revisions"}],"predecessor-version":[{"id":2515,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/posts\/2514\/revisions\/2515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/media\/2516"}],"wp:attachment":[{"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/media?parent=2514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/categories?post=2514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medespoir.ch\/blog\/wp-json\/wp\/v2\/tags?post=2514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}